{"id":31,"count":1,"description":"","link":"http:\/\/selfago.org\/en\/category\/congresses-2\/","name":"Congresses","slug":"congresses-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/selfago.org\/en\/category\/congresses-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe\" \/>\n<meta property=\"og:url\" content=\"http:\/\/selfago.org\/en\/category\/congresses-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/selfago.org\/en\/category\/congresses-2\/\",\"url\":\"http:\/\/selfago.org\/en\/category\/congresses-2\/\",\"name\":\"Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe\",\"isPartOf\":{\"@id\":\"https:\/\/selfago.org\/en\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/selfago.org\/en\/category\/congresses-2\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/selfago.org\/en\/category\/congresses-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/selfago.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congresses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/selfago.org\/en\/#website\",\"url\":\"https:\/\/selfago.org\/en\/\",\"name\":\"Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe\",\"description\":\"Die SELFAGO f\u00f6rdert den wissenschaftlichen Austausch und die Zusammenarbeit in Gyn\u00e4kologie und Geburtshilfe im deutsch-franz\u00f6sischen Raum und dar\u00fcber hinaus. Durch Netzwerke, Kongresse und Forschungsprojekte gestalten wir den internationalen Dialog aktiv mit.\",\"publisher\":{\"@id\":\"https:\/\/selfago.org\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/selfago.org\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/selfago.org\/en\/#organization\",\"name\":\"SELFAGO\",\"url\":\"https:\/\/selfago.org\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/selfago.org\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/selfago.org\/wp-content\/uploads\/2025\/12\/cropped-Logo-Transparent-02-scaled-e1764783827390.png\",\"contentUrl\":\"http:\/\/selfago.org\/wp-content\/uploads\/2025\/12\/cropped-Logo-Transparent-02-scaled-e1764783827390.png\",\"width\":862,\"height\":865,\"caption\":\"SELFAGO\"},\"image\":{\"@id\":\"https:\/\/selfago.org\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/selfago.org\/en\/category\/congresses-2\/","og_locale":"en_US","og_type":"article","og_title":"Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe","og_url":"http:\/\/selfago.org\/en\/category\/congresses-2\/","og_site_name":"Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/selfago.org\/en\/category\/congresses-2\/","url":"http:\/\/selfago.org\/en\/category\/congresses-2\/","name":"Congresses Archive - Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe","isPartOf":{"@id":"https:\/\/selfago.org\/en\/#website"},"breadcrumb":{"@id":"http:\/\/selfago.org\/en\/category\/congresses-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/selfago.org\/en\/category\/congresses-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/selfago.org\/en\/"},{"@type":"ListItem","position":2,"name":"Congresses"}]},{"@type":"WebSite","@id":"https:\/\/selfago.org\/en\/#website","url":"https:\/\/selfago.org\/en\/","name":"Europ\u00e4ische Gesellschaft Deutsch-Franz\u00f6sischer Sprache f\u00fcr Gyn\u00e4kologie und Geburtshilfe","description":"Die SELFAGO f\u00f6rdert den wissenschaftlichen Austausch und die Zusammenarbeit in Gyn\u00e4kologie und Geburtshilfe im deutsch-franz\u00f6sischen Raum und dar\u00fcber hinaus. Durch Netzwerke, Kongresse und Forschungsprojekte gestalten wir den internationalen Dialog aktiv mit.","publisher":{"@id":"https:\/\/selfago.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selfago.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/selfago.org\/en\/#organization","name":"SELFAGO","url":"https:\/\/selfago.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/selfago.org\/en\/#\/schema\/logo\/image\/","url":"http:\/\/selfago.org\/wp-content\/uploads\/2025\/12\/cropped-Logo-Transparent-02-scaled-e1764783827390.png","contentUrl":"http:\/\/selfago.org\/wp-content\/uploads\/2025\/12\/cropped-Logo-Transparent-02-scaled-e1764783827390.png","width":862,"height":865,"caption":"SELFAGO"},"image":{"@id":"https:\/\/selfago.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/selfago.org\/en\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/selfago.org\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/selfago.org\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/selfago.org\/en\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}